{"id":2093,"date":"2025-04-28T14:20:35","date_gmt":"2025-04-28T12:20:35","guid":{"rendered":"https:\/\/www.life-recorgfertplus.eu\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/"},"modified":"2025-04-28T15:08:50","modified_gmt":"2025-04-28T13:08:50","slug":"life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025","status":"publish","type":"post","link":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/","title":{"rendered":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p class=\"\" data-start=\"0\" data-end=\"14\"><strong>28 aprile 2025<\/strong><\/p>\n<p class=\"\" data-start=\"16\" data-end=\"280\">Siamo lieti di annunciare che dal 16 al 18 aprile, il progetto LIFE RECORGFERT PLUS, coordinato da Antonio Scialletti di SBS Steel Belt Systems, ha partecipato alla <strong>3\u00aa Conferenza Internazionale Fertilizers 2025: Turchia e regione del Mar Nero<\/strong>, organizzata da Chem Courier.<\/p>\n<p class=\"\" data-start=\"282\" data-end=\"631\"><span data-teams=\"true\"> Durante l\u2019evento, il Coordinatore del Progetto, Antonio Scialletti, ha presentato LIFE RECORGFERT PLUS<\/span>, con un intervento sul tema &#8220;Fertilizzanti speciali: progetto Life UE per un nuovo fertilizzante organico e un nuovo processo produttivo&#8221;, evidenziando gli obiettivi del progetto, le innovazioni tecnologiche e i risultati attesi&#8221;.<\/p>\n<p class=\"\" data-start=\"633\" data-end=\"895\">Oltre a offrire una preziosa opportunit\u00e0 di networking e divulgazione, la partecipazione a questa conferenza ha contribuito a diffondere la consapevolezza sulle iniziative di sostenibilit\u00e0 e economia circolare del progetto LIFE RECORGFERT PLUS in tutto il mondo.<\/p>\n<p class=\"\" data-start=\"897\" data-end=\"932\">Di seguito alcune foto dell&#8217;evento!<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-5 fusion-gallery-layout-grid fusion-gallery-1\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg\" width=\"468\" height=\"324\" alt=\"Antonio Scialletti presented the LIFE RECORGFERT PLUS project\" title=\"Antonio Scialletti presented the LIFE RECORGFERT PLUS project\" aria-label=\"Antonio Scialletti presented the LIFE RECORGFERT PLUS project\" class=\"img-responsive wp-image-2083\" srcset=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project-200x138.jpg 200w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project-400x277.jpg 400w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg 468w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/LIFE-RecOrgFert-PLus-3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.png\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/LIFE-RecOrgFert-PLus-3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.png\" width=\"479\" height=\"361\" alt=\"LIFE RecOrgFert PLus 3nd International Conference Fertilizers 2025 - Turkiye and Black Sea region, organized by Chem Courier\" title=\"LIFE RecOrgFert PLus 3nd International Conference Fertilizers 2025 &#8211; Turkiye and Black Sea region, organized by Chem Courier\" aria-label=\"LIFE RecOrgFert PLus 3nd International Conference Fertilizers 2025 &#8211; Turkiye and Black Sea region, organized by Chem Courier\" class=\"img-responsive wp-image-2091\" srcset=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/LIFE-RecOrgFert-PLus-3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier-200x151.png 200w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/LIFE-RecOrgFert-PLus-3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier-400x301.png 400w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/LIFE-RecOrgFert-PLus-3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.png 479w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg\" width=\"467\" height=\"353\" alt=\"Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project\" title=\"Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project\" aria-label=\"Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project\" class=\"img-responsive wp-image-2089\" srcset=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project-200x151.jpg 200w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project-400x302.jpg 400w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/Project-Coordinator-Antonio-Scialletti-presented-the-LIFE-RECORGFERT-PLUS-project.jpg 467w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\" width=\"463\" height=\"352\" alt=\"3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier\" title=\"3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier\" aria-label=\"3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier\" class=\"img-responsive wp-image-2087\" srcset=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier-200x152.jpg 200w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier-400x304.jpg 400w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg 463w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025.jpg\" width=\"1102\" height=\"579\" alt=\"\" title=\"3nd-International-Conference-Fertilizers-2025\" aria-label=\"3nd-International-Conference-Fertilizers-2025\" class=\"img-responsive wp-image-2085\" srcset=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-200x105.jpg 200w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-400x210.jpg 400w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-600x315.jpg 600w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-800x420.jpg 800w, https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025.jpg 1102w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,39,36,38],"tags":[],"class_list":["post-2093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-pubblici","category-eventi-pubblici-it","category-news-it","category-news-it-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS<\/title>\n<meta name=\"description\" content=\"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 &gt;&gt;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS\" \/>\n<meta property=\"og:description\" content=\"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 &gt;&gt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Life-RecOrgFertPLUS\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T12:20:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T13:08:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"463\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sara Attan\u00e0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara Attan\u00e0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/\"},\"author\":{\"name\":\"Sara Attan\u00e0\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#\\\/schema\\\/person\\\/8d82401b46428e94d204c23af9a2aa30\"},\"headline\":\"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025\",\"datePublished\":\"2025-04-28T12:20:35+00:00\",\"dateModified\":\"2025-04-28T13:08:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/\"},\"wordCount\":772,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\",\"articleSection\":[\"Eventi Pubblici\",\"Eventi pubblici\",\"News\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/\",\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/\",\"name\":\"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\",\"datePublished\":\"2025-04-28T12:20:35+00:00\",\"dateModified\":\"2025-04-28T13:08:50+00:00\",\"description\":\"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 >>\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\",\"contentUrl\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg\",\"width\":463,\"height\":352,\"caption\":\"3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/\",\"name\":\"Life-RecOrgFertPLUS\",\"description\":\"Organic-mineral fertilizers by using recovered sulphur &amp; orange wastes as sustainable soil recovery from desertification\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#organization\",\"name\":\"LIFE RecOrgFert PLUS\",\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Favicon-167x167-1.png\",\"contentUrl\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Favicon-167x167-1.png\",\"width\":167,\"height\":167,\"caption\":\"LIFE RecOrgFert PLUS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/life-recorgfert-plus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/#\\\/schema\\\/person\\\/8d82401b46428e94d204c23af9a2aa30\",\"name\":\"Sara Attan\u00e0\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g\",\"caption\":\"Sara Attan\u00e0\"},\"url\":\"https:\\\/\\\/www.life-recorgfertplus.eu\\\/it\\\/author\\\/sara-attana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS","description":"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 >>","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/","og_locale":"it_IT","og_type":"article","og_title":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS","og_description":"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 >>","og_url":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/","og_site_name":"Life-RecOrgFertPLUS","article_published_time":"2025-04-28T12:20:35+00:00","article_modified_time":"2025-04-28T13:08:50+00:00","og_image":[{"width":463,"height":352,"url":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg","type":"image\/jpeg"}],"author":"Sara Attan\u00e0","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sara Attan\u00e0","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#article","isPartOf":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/"},"author":{"name":"Sara Attan\u00e0","@id":"https:\/\/www.life-recorgfertplus.eu\/#\/schema\/person\/8d82401b46428e94d204c23af9a2aa30"},"headline":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025","datePublished":"2025-04-28T12:20:35+00:00","dateModified":"2025-04-28T13:08:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/"},"wordCount":772,"commentCount":0,"publisher":{"@id":"https:\/\/www.life-recorgfertplus.eu\/#organization"},"image":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg","articleSection":["Eventi Pubblici","Eventi pubblici","News","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/","url":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/","name":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025 - Life-RecOrgFertPLUS","isPartOf":{"@id":"https:\/\/www.life-recorgfertplus.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg","datePublished":"2025-04-28T12:20:35+00:00","dateModified":"2025-04-28T13:08:50+00:00","description":"Siamo lieti di annunciare che il progetto LIFE RECORGFERT PLUS ha partecipato alla 3\u00aa Conferenza Internazionale Fertilizers 2025. Leggi di pi\u00f9 >>","breadcrumb":{"@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#primaryimage","url":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg","contentUrl":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2025\/04\/3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier.jpg","width":463,"height":352,"caption":"3nd-International-Conference-Fertilizers-2025-Turkiye-and-Black-Sea-region-organized-by-Chem-Courier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.life-recorgfertplus.eu\/it\/life-recorgfert-plus-alla-3a-conferenza-internazionale-fertilizers-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.life-recorgfertplus.eu\/it\/"},{"@type":"ListItem","position":2,"name":"LIFE RECORGFERT PLUS alla 3\u00aa Conferenza Internazionale Fertilizers 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.life-recorgfertplus.eu\/#website","url":"https:\/\/www.life-recorgfertplus.eu\/","name":"Life-RecOrgFertPLUS","description":"Organic-mineral fertilizers by using recovered sulphur &amp; orange wastes as sustainable soil recovery from desertification","publisher":{"@id":"https:\/\/www.life-recorgfertplus.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.life-recorgfertplus.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.life-recorgfertplus.eu\/#organization","name":"LIFE RecOrgFert PLUS","url":"https:\/\/www.life-recorgfertplus.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.life-recorgfertplus.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2022\/02\/Favicon-167x167-1.png","contentUrl":"https:\/\/www.life-recorgfertplus.eu\/wp-content\/uploads\/2022\/02\/Favicon-167x167-1.png","width":167,"height":167,"caption":"LIFE RecOrgFert PLUS"},"image":{"@id":"https:\/\/www.life-recorgfertplus.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/life-recorgfert-plus"]},{"@type":"Person","@id":"https:\/\/www.life-recorgfertplus.eu\/#\/schema\/person\/8d82401b46428e94d204c23af9a2aa30","name":"Sara Attan\u00e0","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94feeb1882db141a3f631a766c2e342b905fb15f4ad47eef51eef813789ea357?s=96&d=mm&r=g","caption":"Sara Attan\u00e0"},"url":"https:\/\/www.life-recorgfertplus.eu\/it\/author\/sara-attana\/"}]}},"_links":{"self":[{"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/posts\/2093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/comments?post=2093"}],"version-history":[{"count":6,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/posts\/2093\/revisions"}],"predecessor-version":[{"id":2103,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/posts\/2093\/revisions\/2103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/media\/2087"}],"wp:attachment":[{"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/media?parent=2093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/categories?post=2093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.life-recorgfertplus.eu\/it\/wp-json\/wp\/v2\/tags?post=2093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}